{"id":10881,"date":"2024-04-06T18:09:04","date_gmt":"2024-04-06T18:09:04","guid":{"rendered":"https:\/\/www.welphi.com\/software\/"},"modified":"2025-10-05T09:29:24","modified_gmt":"2025-10-05T09:29:24","slug":"software","status":"publish","type":"page","link":"https:\/\/www.welphi.com\/pt-pt\/software\/","title":{"rendered":"Software"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10881\" class=\"elementor elementor-10881 elementor-15\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c03bc0a e-flex e-con-boxed e-con e-parent\" data-id=\"c03bc0a\" data-element_type=\"container\" id=\"home\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope  &gt; .elementor-element:not(.lqd-exclude-parent-ca) &gt; .elementor-widget-container, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-adv-txt-fig, :scope  &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1000,&quot;delay&quot;:75,&quot;ease&quot;:&quot;expo.out&quot;,&quot;initValues&quot;:{&quot;y&quot;:&quot;100px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-element elementor-element-27d046df e-con-full e-flex e-con e-child\" data-id=\"27d046df\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f13d316 elementor-mobile-align-center elementor-widget-mobile__width-inherit elementor-widget elementor-widget-ld_button\" data-id=\"f13d316\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a\n\t\t\t\tclass=\"elementor-button btn btn-solid btn-xsm btn-icon-shaped btn-has-label\"\t\t\t>\n\t\t\t\t\t\t\t\t\t<span data-text=\"Software de Question\u00e1rio Online\" class=\"btn-txt\">\n\t\t\t\t\t\tSoftware de Question\u00e1rio Online\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8519da elementor-widget__width-inherit elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"e8519da\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce638813f\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h1 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h1\"  > Welphi<\/h1>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cb91b17 elementor-widget__width-inherit elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"4cb91b17\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce63887d3\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title ld-gradient-heading lqd-highlight-classic lqd-highlight-grow-left h2\"  > M\u00e9todos para uma tomada de decis\u00e3o <\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ff784f4 elementor-widget__width-initial elementor-widget elementor-widget-hub_fancy_heading lqd-el-has-inner-anim\" data-id=\"6ff784f4\" data-element_type=\"widget\" data-settings=\"{&quot;enable_split&quot;:&quot;true&quot;,&quot;split_type&quot;:&quot;lines&quot;}\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce6388d8a\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left lqd-split-lines p\"  data-split-text=\"true\" data-split-options='{\"type\":\"lines\"}'> Constr\u00f3i question\u00e1rios que implementam o m\u00e9todo Delphi ou MCDA para uma tomada de decis\u00e3o s\u00f3lida e baseada em prefer\u00eancias em diversos dom\u00ednios.<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-582eb683 elementor-widget-tablet__width-inherit elementor-widget-mobile__width-initial elementor-hidden-mobile elementor-widget elementor-widget-ld_button\" data-id=\"582eb683\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/app2.welphi.com\/Pages\/LoginPage.aspx?trial=1\" target=\"_blank\" rel=\"nofollow noopener\" class=\"elementor-button btn btn-solid btn-hover-txt-switch btn-hover-txt-switch-y btn-sm btn-icon-right btn-has-label\">\n\t\t\t\t\t\t\t\t\t<span data-text=\"Teste Gratuito\" class=\"btn-txt\" data-transition-delay=\"true\" data-delay-options=\"{&quot;elements&quot;: &quot;.lqd-chars&quot;, &quot;delayType&quot;: &quot;animation&quot;, &quot;startDelay&quot;: 0, &quot;delayBetween&quot;: 32.5}\" data-split-text=\"true\" data-split-options=\"{&quot;type&quot;: &quot;chars, words&quot;}\">\n\t\t\t\t\t\tTeste Gratuito\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-md-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66050e7f elementor-widget-tablet__width-inherit elementor-widget-mobile__width-initial elementor-hidden-mobile button-demo elementor-widget elementor-widget-ld_button\" data-id=\"66050e7f\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a\n\t\t\t\tclass=\"elementor-button btn btn-solid btn-sm btn-icon-right btn-has-label\"\t\t\t>\n\t\t\t\t\t\t\t\t\t<span data-text=\"Marcar Demo\" class=\"btn-txt\">\n\t\t\t\t\t\tMarcar Demo\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6143a3 elementor-widget-tablet__width-inherit elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-ld_button\" data-id=\"c6143a3\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/app2.welphi.com\/Pages\/LoginPage.aspx?trial=1\" target=\"_blank\" rel=\"nofollow noopener\" class=\"elementor-button btn btn-solid btn-hover-txt-switch btn-hover-txt-switch-y btn-sm btn-icon-right btn-has-label\">\n\t\t\t\t\t\t\t\t\t<span data-text=\"Testar \" class=\"btn-txt\" data-transition-delay=\"true\" data-delay-options=\"{&quot;elements&quot;: &quot;.lqd-chars&quot;, &quot;delayType&quot;: &quot;animation&quot;, &quot;startDelay&quot;: 0, &quot;delayBetween&quot;: 32.5}\" data-split-text=\"true\" data-split-options=\"{&quot;type&quot;: &quot;chars, words&quot;}\">\n\t\t\t\t\t\tTestar \t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-md-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b2893c elementor-widget-tablet__width-inherit elementor-widget-mobile__width-initial elementor-hidden-desktop elementor-hidden-tablet button-demo elementor-widget elementor-widget-ld_button\" data-id=\"9b2893c\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a\n\t\t\t\tclass=\"elementor-button btn btn-solid btn-sm btn-icon-right btn-has-label\"\t\t\t>\n\t\t\t\t\t\t\t\t\t<span data-text=\"Demo\" class=\"btn-txt\">\n\t\t\t\t\t\tDemo\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-218cb447 elementor-widget__width-inherit elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"218cb447\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce638b8be\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Teste gratuito de 14 dias - Suporte exclusivo - Ambiente em cloud<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope  &gt; .elementor-element:not(.lqd-exclude-parent-ca) &gt; .elementor-widget-container, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-adv-txt-fig, :scope  &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1000,&quot;startDelay&quot;:500,&quot;delay&quot;:70,&quot;ease&quot;:&quot;expo.out&quot;,&quot;initValues&quot;:{&quot;x&quot;:&quot;-20px&quot;,&quot;y&quot;:&quot;100px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;x&quot;:&quot;0px&quot;,&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-element elementor-element-671e907 e-con-full e-flex e-con e-child\" data-id=\"671e907\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59092022 elementor-widget-mobile__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"59092022\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \" data-float=\"ease-in\">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1512\" height=\"924\" src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/03\/welphi_qualitative_graph_boxplot.jpeg\" class=\"attachment-full size-full wp-image-10652\" alt=\"Survey-Software-Consensus\" srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/03\/welphi_qualitative_graph_boxplot.jpeg 1512w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/03\/welphi_qualitative_graph_boxplot-300x183.jpeg 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/03\/welphi_qualitative_graph_boxplot-1024x626.jpeg 1024w\" sizes=\"(max-width: 1512px) 100vw, 1512px\" itemprop=\"image\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope  &gt; .elementor-element:not(.lqd-exclude-parent-ca) &gt; .elementor-widget-container, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-adv-txt-fig, :scope  &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1000,&quot;startDelay&quot;:1250,&quot;delay&quot;:70,&quot;ease&quot;:&quot;expo.out&quot;,&quot;initValues&quot;:{&quot;y&quot;:&quot;50px&quot;,&quot;scaleX&quot;:0.5,&quot;scaleY&quot;:0.5,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;scaleX&quot;:1,&quot;scaleY&quot;:1,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-element elementor-element-433eefe5 e-con-full e-flex e-con e-parent\" data-id=\"433eefe5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2e5450 e-con-full e-flex e-con e-child\" data-id=\"f2e5450\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f09ca6e elementor-widget__width-inherit elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"5f09ca6e\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce638e42e\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Utilizado por organiza\u00e7\u00f5es de excel\u00eancia em todo o mundo<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8538f8 elementor-widget elementor-widget-ld_carousel\" data-id=\"b8538f8\" data-element_type=\"widget\" data-widget_type=\"ld_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"carousel-container pos-rel carousel-nav-shaped\" id=\"\" >\n\n\t\t\t<div class=\"carousel-items pos-rel lqd-fade-sides\"  data-lqd-flickity='{\"marquee\":true,\"equalHeightCells\":true,\"middleAlignContent\":true,\"draggable\":false,\"pauseAutoPlayOnHover\":false}'>\n\n\t\t\t\t\t\t\t\t<div class=\"flickity-viewport pos-rel w-100 overflow-hidden\">\n\t\t\t\t\t<div class=\"flickity-slider d-flex w-100 h-100 pos-rel\" style=\"left: 0; transform: translateX(0%);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center align-items-center elementor-repeater-item-447042f\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\n\t\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"alignnone wp-image-8031 size-medium\" src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/GMC_Wordmark_2008_RGB-300x55.jpg\" alt=\"\" width=\"300\" height=\"55\" srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/GMC_Wordmark_2008_RGB-300x55.jpg 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/GMC_Wordmark_2008_RGB-1024x188.jpg 1024w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/GMC_Wordmark_2008_RGB.jpg 1476w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center align-items-center elementor-repeater-item-4ee2f66\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\n\t\t\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"alignnone wp-image-8030 size-medium\" src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/P_HEOR_stacked_RGB-300x82.png\" alt=\"\" width=\"300\" height=\"82\" srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/P_HEOR_stacked_RGB-300x82.png 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/P_HEOR_stacked_RGB-1024x281.png 1024w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/P_HEOR_stacked_RGB.png 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center align-items-center elementor-repeater-item-7229065\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\n\t\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8029 size-medium\" src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/lse-logo-300x107.png\" alt=\"\" width=\"300\" height=\"107\" srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/lse-logo-300x107.png 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/lse-logo-1024x367.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center align-items-center elementor-repeater-item-59a715c\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\n\t\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8028 size-medium\" src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Logo8_FBMC-300x124.png\" alt=\"\" width=\"300\" height=\"124\" srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Logo8_FBMC-300x124.png 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Logo8_FBMC.png 632w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center align-items-center elementor-repeater-item-a6c4616\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\n\t\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8027 size-full\" src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Logo4_EURO-HEALTHY.png\" alt=\"\" width=\"288\" height=\"143\" \/><\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center align-items-center elementor-repeater-item-6599355\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\n\t\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8026 size-full\" src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Picture-1.png\" alt=\"\" width=\"144\" height=\"44\" \/><\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"carousel-item d-flex flex-column justify-content-center align-items-center elementor-repeater-item-183f7fd\">\n\t\t\t\t\t\t\t\t<div class=\"carousel-item-inner pos-rel w-100\">\n\t\t\t\t\t\t\t\t\t<div class=\"carousel-item-content pos-rel w-100\">\n\n\t\t\t\t\t\t\t\t\t\t<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8025 size-medium\" src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/logo-300x77.png\" alt=\"\" width=\"300\" height=\"77\" srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/logo-300x77.png 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/logo.png 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e8b225a e-flex e-con-boxed e-con e-parent\" data-id=\"5e8b225a\" data-element_type=\"container\" id=\"features\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3d8d8752 e-con-full e-flex e-con e-child\" data-id=\"3d8d8752\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-766efc6c elementor-widget elementor-widget-ld_fancy_image\" data-id=\"766efc6c\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1001\" height=\"1001\" src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/Welphi-Delphi-MCDA-MACBETH-Method-survey-software.webp\" class=\"attachment-full size-full wp-image-12127\" alt=\"\" srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/Welphi-Delphi-MCDA-MACBETH-Method-survey-software.webp 1001w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/Welphi-Delphi-MCDA-MACBETH-Method-survey-software-300x300.webp 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/Welphi-Delphi-MCDA-MACBETH-Method-survey-software-150x150.webp 150w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/Welphi-Delphi-MCDA-MACBETH-Method-survey-software-320x320.webp 320w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/Welphi-Delphi-MCDA-MACBETH-Method-survey-software-760x760.webp 760w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" itemprop=\"image\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope  &gt; .elementor-element:not(.lqd-exclude-parent-ca) &gt; .elementor-widget-container, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope  &gt; .elementor-widget-hub_fancy_heading .lqd-adv-txt-fig, :scope  &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1000,&quot;ease&quot;:&quot;expo.out&quot;,&quot;initValues&quot;:{&quot;x&quot;:&quot;70px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;x&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-element elementor-element-70b2aa4c e-con-full e-flex e-con e-child\" data-id=\"70b2aa4c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71893cdc elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"71893cdc\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce63966d5\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > A ferramentas<br>que precisa para compreender<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-251cab elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"251cab\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce6396cad\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title ld-gradient-heading lqd-highlight-classic lqd-highlight-grow-left h2\"  > as prefer\u00eancias e opini\u00f5es das pessoas.<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69dbdc96 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"69dbdc96\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce63973ca\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > A Welphi \u00e9 uma plataforma \u00fanica que permite construir question\u00e1rios para recolher as prefer\u00eancias dos participantes, implementar m\u00e9todos cientificamente robustos e melhorar a tomada de decis\u00f5es.  <\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24bde88 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"24bde88\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce63979b4\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Implemente facilmente a T\u00e9cnica <span style=\"color: #0A2156\">Delphi<\/span> para selecionar crit\u00e9rios, validar declara\u00e7\u00f5es, criar\npol\u00edticas, definir diretrizes ou chegar a consensos em qualquer \u00e1rea.<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-394f9f0 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"394f9f0\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce6397f16\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > A Welphi tamb\u00e9m lhe permite criar question\u00e1rios de elicita\u00e7\u00e3o de prefer\u00eancias de <span style=\"color: #0A2156\">An\u00e1lise de Decis\u00e3o Multi-crit\u00e9rio (MCDA)<\/span>, completos com <span style=\"color: #0A2156\">Swing-Weighting <\/span> e\nscoring, implementando a <span style=\"color: #0A2156\">t\u00e9cnica MACBETH<\/span>, melhorando assim o seu processo de tomada de decis\u00e3o.<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68e2936 elementor-widget__width-auto elementor-widget elementor-widget-ld_button\" data-id=\"68e2936\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=CI8M-EPXaH8\" target=\"_blank\" rel=\"nofollow noopener\" class=\"elementor-button btn btn-naked fresco btn-icon-left btn-icon-circle btn-icon-xlg btn-icon-shaped btn-icon-solid btn-has-label\">\n\t\t\t\t\t\t\t\t\t<span data-text=\"&lt;small style=&quot;font-size:11px&quot;&gt;Assistir \u00e0 demonstra\u00e7\u00e3o&lt;\/small&gt; Ver como funciona\" class=\"btn-txt\">\n\t\t\t\t\t\t<small style=\"font-size:11px\">Assistir \u00e0 demonstra\u00e7\u00e3o<\/small> Ver como funciona\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-play\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f8653e1 e-flex e-con-boxed e-con e-parent\" data-id=\"f8653e1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-edfc502 e-con-full e-flex e-con e-child\" data-id=\"edfc502\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-097e046 e-con-full e-flex e-con e-child\" data-id=\"097e046\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a62c428 e-con-full e-flex e-con e-child\" data-id=\"a62c428\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fd2842a e-con-full e-flex e-con e-child\" data-id=\"fd2842a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87e475b elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"87e475b\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce63993b8\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h3\"  > Teste gratuito de 14 dias<\/h3>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a6c459b e-con-full e-flex e-con e-child\" data-id=\"a6c459b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a83525 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-ld_button\" data-id=\"0a83525\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/app2.welphi.com\/Pages\/LoginPage.aspx?trial=1\" class=\"elementor-button btn btn-solid btn-hover-txt-switch btn-hover-txt-switch-y btn-xsm btn-icon-right btn-has-label\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t<span data-text=\"Quero Testar\" class=\"btn-txt\" data-transition-delay=\"true\" data-delay-options=\"{&quot;elements&quot;: &quot;.lqd-chars&quot;, &quot;delayType&quot;: &quot;animation&quot;, &quot;startDelay&quot;: 0, &quot;delayBetween&quot;: 32.5}\" data-split-text=\"true\" data-split-options=\"{&quot;type&quot;: &quot;chars, words&quot;}\">\n\t\t\t\t\t\tQuero Testar\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-md-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope .e-con-inner &gt; .elementor-element:not(.lqd-exclude-parent-ca) &gt; .elementor-widget-container, :scope .e-con-inner &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope .e-con-inner &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope .e-con-inner &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope .e-con-inner &gt; .elementor-widget-hub_fancy_heading .lqd-adv-txt-fig, :scope .e-con-inner &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li, :scope .e-con:not([data-parallax]) .elementor-element &gt; .elementor-widget-container, :scope .e-con:not([data-parallax]) .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope .e-con:not([data-parallax]) .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope .e-con:not([data-parallax]) .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope .e-con:not([data-parallax]) .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1000,&quot;delay&quot;:65,&quot;ease&quot;:&quot;expo.out&quot;,&quot;initValues&quot;:{&quot;y&quot;:&quot;50px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-element elementor-element-54218108 e-flex e-con-boxed e-con e-parent\" data-id=\"54218108\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-38921d9c e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"38921d9c\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e0b324c e-con-full e-flex e-con e-child\" data-id=\"1e0b324c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70ac6ef3 elementor-widget elementor-widget-hub_fancy_heading lqd-el-has-inner-anim\" data-id=\"70ac6ef3\" data-element_type=\"widget\" data-settings=\"{&quot;enable_split&quot;:&quot;true&quot;,&quot;split_type&quot;:&quot;lines&quot;}\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce639a3f3\" class=\"ld-fancy-heading pos-rel mask-text\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left lqd-split-lines h2\"  data-split-text=\"true\" data-split-options='{\"type\":\"lines\"}'> Processo simplificado<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28e9651c elementor-widget-tablet__width-inherit elementor-widget elementor-widget-hub_fancy_heading lqd-el-has-inner-anim\" data-id=\"28e9651c\" data-element_type=\"widget\" data-settings=\"{&quot;enable_split&quot;:&quot;true&quot;,&quot;split_type&quot;:&quot;lines&quot;}\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce639aa6c\" class=\"ld-fancy-heading pos-rel mask-text\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left lqd-split-lines p\"  data-split-text=\"true\" data-split-options='{\"type\":\"lines\"}'> Todas as ferramentas de que precisas para aumentar os teus n\u00edveis de participa\u00e7\u00e3o<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cd65ac4 elementor-widget__width-inherit e-transform elementor-hidden-mobile elementor-widget elementor-widget-ld_tabs\" data-id=\"5cd65ac4\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"ld_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"lqd-tabs lqd-tabs-style-6 lqd-tabs-nav-iconbox lqd-tabs-nav-icon-inline d-flex flex-wrap lqd-tabs-nav-items-not-expanded flex-row-reverse 5cd65ac4 lqd-nav-underline-\" data-tabs-options=\"{&quot;trigger&quot;:&quot;click&quot;}\">\n\n\t\t\t<nav class=\"lqd-tabs-nav-wrap\">\n\t\t\t\t<ul class=\"reset-ul lqd-tabs-nav d-flex flex-column lqd-css-sticky pos-rel\" role=\"tablist\"><li data-controls=\"lqd-tab-1551\" role=\"presentation\" class=\"elementor-repeater-item-f432fc3 active font-weight-medium\"><a class=\"d-block pt-3 pb-3 border-radius-4\" href=\"#lqd-tab-1551\" data-bs-target=\"#lqd-tab-1551\" aria-expanded=\"false\" aria-controls=\"lqd-tab-1551\" role=\"tab\" data-toggle=\"tab\" data-bs-toggle=\"tab\"><span class=\"lqd-tabs-nav-icon-icon d-inline-flex align-items-center justify-content-center me-5 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-num-1\"><\/i><\/span><span class=\"lqd-tabs-nav-txt\">Crie processos e rondas<\/span><\/a><\/li><li data-controls=\"lqd-tab-1552\" role=\"presentation\" class=\"elementor-repeater-item-60c7c23 font-weight-medium\"><a class=\"d-block pt-3 pb-3 border-radius-4\" href=\"#lqd-tab-1552\" data-bs-target=\"#lqd-tab-1552\" aria-expanded=\"false\" aria-controls=\"lqd-tab-1552\" role=\"tab\" data-toggle=\"tab\" data-bs-toggle=\"tab\"><span class=\"lqd-tabs-nav-icon-icon d-inline-flex align-items-center justify-content-center me-5 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-num-2\"><\/i><\/span><span class=\"lqd-tabs-nav-txt\">Convite e envie lembretes<\/span><\/a><\/li><li data-controls=\"lqd-tab-1553\" role=\"presentation\" class=\"elementor-repeater-item-8e6a7ce font-weight-medium\"><a class=\"d-block pt-3 pb-3 border-radius-4\" href=\"#lqd-tab-1553\" data-bs-target=\"#lqd-tab-1553\" aria-expanded=\"false\" aria-controls=\"lqd-tab-1553\" role=\"tab\" data-toggle=\"tab\" data-bs-toggle=\"tab\"><span class=\"lqd-tabs-nav-icon-icon d-inline-flex align-items-center justify-content-center me-5 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-num-3\"><\/i><\/span><span class=\"lqd-tabs-nav-txt\">Monitorize a participa\u00e7\u00e3o<\/span><\/a><\/li><li data-controls=\"lqd-tab-1554\" role=\"presentation\" class=\"elementor-repeater-item-946ce76 font-weight-medium\"><a class=\"d-block pt-3 pb-3 border-radius-4\" href=\"#lqd-tab-1554\" data-bs-target=\"#lqd-tab-1554\" aria-expanded=\"false\" aria-controls=\"lqd-tab-1554\" role=\"tab\" data-toggle=\"tab\" data-bs-toggle=\"tab\"><span class=\"lqd-tabs-nav-icon-icon d-inline-flex align-items-center justify-content-center me-5 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-num-4\"><\/i><\/span><span class=\"lqd-tabs-nav-txt\">Recolha de dados<\/span><\/a><\/li><\/ul>\t\t\t\t\t\t\t<\/nav>\n\n\t\t\t<div class=\"lqd-tabs-content pe-5 pos-rel\"><div id=\"lqd-tab-1551\" role=\"tabpanel\" class=\"lqd-tabs-pane fade active in\"><style>.elementor-7158 .elementor-element.elementor-element-44210468{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;}.elementor-7158 .elementor-element.elementor-element-4420f3ec{width:var( --container-widget-width, 770px );max-width:770px;--container-widget-width:770px;--container-widget-flex-grow:0;}.elementor-7158 .elementor-element.elementor-element-4420f3ec > .elementor-widget-container{margin:-30% -10% -20% 0%;}@media(max-width:1024px){.elementor-7158 .elementor-element.elementor-element-4420f3ec > .elementor-widget-container{margin:-12% -10% -20% 0%;}}@media(max-width:767px){.elementor-7158 .elementor-element.elementor-element-4420f3ec > .elementor-widget-container{margin:-12% -16% -10% -18%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"7158\" class=\"elementor elementor-7158\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-44210468 e-flex e-con-boxed e-con e-parent\" data-id=\"44210468\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4420f3ec elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"4420f3ec\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1515\" height=\"1219\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1515 1219&#039;%2F%3E\" class=\"attachment-full size-full wp-image-11980 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/04\/create-processes-and-round-welphi-survey-software.webp\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/04\/create-processes-and-round-welphi-survey-software.webp 1515w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/04\/create-processes-and-round-welphi-survey-software-300x241.webp 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/04\/create-processes-and-round-welphi-survey-software-1024x824.webp 1024w\" data-sizes=\"(max-width: 1515px) 100vw, 1515px\" data-aspect=\"1.2428219852338\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t <\/div><div id=\"lqd-tab-1552\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.elementor-12131 .elementor-element.elementor-element-62b78487{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;}.elementor-12131 .elementor-element.elementor-element-55cc8ad{width:var( --container-widget-width, 770px );max-width:770px;--container-widget-width:770px;--container-widget-flex-grow:0;}.elementor-12131 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-38% -10% -20% 0%;}@media(max-width:1024px){.elementor-12131 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-12% -10% -20% 0%;}}@media(max-width:767px){.elementor-12131 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-12% -16% -10% -18%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"12131\" class=\"elementor elementor-12131\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-62b78487 e-flex e-con-boxed e-con e-parent\" data-id=\"62b78487\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55cc8ad elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"55cc8ad\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"853\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1060 853&#039;%2F%3E\" class=\"attachment-full size-full wp-image-8311 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-Invitation-Customized-Messages.png\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-Invitation-Customized-Messages.png 1060w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-Invitation-Customized-Messages-300x241.png 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-Invitation-Customized-Messages-1024x824.png 1024w\" data-sizes=\"(max-width: 1060px) 100vw, 1060px\" data-aspect=\"1.242672919109\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t <\/div><div id=\"lqd-tab-1553\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.elementor-8285 .elementor-element.elementor-element-b46828c{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;}.elementor-8285 .elementor-element.elementor-element-3b198d36{width:var( --container-widget-width, 770px );max-width:770px;--container-widget-width:770px;--container-widget-flex-grow:0;}.elementor-8285 .elementor-element.elementor-element-3b198d36 > .elementor-widget-container{margin:-38% -10% -20% 0%;}@media(max-width:1024px){.elementor-8285 .elementor-element.elementor-element-3b198d36 > .elementor-widget-container{margin:-12% -10% -20% 0%;}}@media(max-width:767px){.elementor-8285 .elementor-element.elementor-element-3b198d36 > .elementor-widget-container{margin:-12% -16% -10% -18%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8285\" class=\"elementor elementor-8285\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-b46828c e-flex e-con-boxed e-con e-parent\" data-id=\"b46828c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b198d36 elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"3b198d36\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1211\" height=\"974\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1211 974&#039;%2F%3E\" class=\"attachment-full size-full wp-image-8303 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Survey-Round-Statistics.png\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Survey-Round-Statistics.png 1211w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Survey-Round-Statistics-300x241.png 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Survey-Round-Statistics-1024x824.png 1024w\" data-sizes=\"(max-width: 1211px) 100vw, 1211px\" data-aspect=\"1.2433264887064\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t <\/div><div id=\"lqd-tab-1554\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.elementor-8310 .elementor-element.elementor-element-62b78487{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;}.elementor-8310 .elementor-element.elementor-element-55cc8ad{width:var( --container-widget-width, 770px );max-width:770px;--container-widget-width:770px;--container-widget-flex-grow:0;}.elementor-8310 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-38% -10% -20% 0%;}@media(max-width:1024px){.elementor-8310 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-12% -10% -20% 0%;}}@media(max-width:767px){.elementor-8310 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-12% -16% -10% -18%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8310\" class=\"elementor elementor-8310\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-62b78487 e-flex e-con-boxed e-con e-parent\" data-id=\"62b78487\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55cc8ad elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"55cc8ad\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1515\" height=\"1219\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1515 1219&#039;%2F%3E\" class=\"attachment-full size-full wp-image-11993 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-survey-software-Collect-demographics.webp\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-survey-software-Collect-demographics.webp 1515w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-survey-software-Collect-demographics-300x241.webp 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-survey-software-Collect-demographics-1024x824.webp 1024w\" data-sizes=\"(max-width: 1515px) 100vw, 1515px\" data-aspect=\"1.2428219852338\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ee5ec7 elementor-widget__width-inherit e-transform elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-ld_tabs\" data-id=\"9ee5ec7\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"ld_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"lqd-tabs lqd-tabs-style-14 lqd-tabs-has-nav-arrows d-flex lqd-tabs-nav-items-not-expanded flex-column 9ee5ec7 lqd-nav-underline-\" data-tabs-options=\"{&quot;translateNav&quot;:true}\">\n\n\t\t\t<nav class=\"lqd-tabs-nav-wrap mb-3\">\n\t\t\t\t<ul class=\"reset-ul lqd-tabs-nav d-flex align-items-center mb-6 pos-rel\" role=\"tablist\"><li data-controls=\"lqd-tab-1661\" role=\"presentation\" class=\"elementor-repeater-item-f432fc3 active\"><a class=\"d-inline-flex align-items-center border-radius-circle\" href=\"#lqd-tab-1661\" data-bs-target=\"#lqd-tab-1661\" aria-expanded=\"false\" aria-controls=\"lqd-tab-1661\" role=\"tab\" data-toggle=\"tab\" data-bs-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\" data-txt=\"Crie processos e rondas\"><span>Crie processos e rondas<span><\/span><\/a><\/li><li data-controls=\"lqd-tab-1662\" role=\"presentation\" class=\"elementor-repeater-item-60c7c23\"><a class=\"d-inline-flex align-items-center border-radius-circle\" href=\"#lqd-tab-1662\" data-bs-target=\"#lqd-tab-1662\" aria-expanded=\"false\" aria-controls=\"lqd-tab-1662\" role=\"tab\" data-toggle=\"tab\" data-bs-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\" data-txt=\"Convite e lembretes\"><span>Convite e lembretes<span><\/span><\/a><\/li><li data-controls=\"lqd-tab-1663\" role=\"presentation\" class=\"elementor-repeater-item-8e6a7ce\"><a class=\"d-inline-flex align-items-center border-radius-circle\" href=\"#lqd-tab-1663\" data-bs-target=\"#lqd-tab-1663\" aria-expanded=\"false\" aria-controls=\"lqd-tab-1663\" role=\"tab\" data-toggle=\"tab\" data-bs-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\" data-txt=\"Monitorize a participa\u00e7\u00e3o\"><span>Monitorize a participa\u00e7\u00e3o<span><\/span><\/a><\/li><li data-controls=\"lqd-tab-1664\" role=\"presentation\" class=\"elementor-repeater-item-946ce76\"><a class=\"d-inline-flex align-items-center border-radius-circle\" href=\"#lqd-tab-1664\" data-bs-target=\"#lqd-tab-1664\" aria-expanded=\"false\" aria-controls=\"lqd-tab-1664\" role=\"tab\" data-toggle=\"tab\" data-bs-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\" data-txt=\"Recolha de dados\"><span>Recolha de dados<span><\/span><\/a><\/li><\/ul>\t\t\t\t\t\t\t<\/nav>\n\n\t\t\t<div class=\"lqd-tabs-content pos-rel\"><div id=\"lqd-tab-1661\" role=\"tabpanel\" class=\"lqd-tabs-pane fade active in\"><style>.elementor-7158 .elementor-element.elementor-element-44210468{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;}.elementor-7158 .elementor-element.elementor-element-4420f3ec{width:var( --container-widget-width, 770px );max-width:770px;--container-widget-width:770px;--container-widget-flex-grow:0;}.elementor-7158 .elementor-element.elementor-element-4420f3ec > .elementor-widget-container{margin:-30% -10% -20% 0%;}@media(max-width:1024px){.elementor-7158 .elementor-element.elementor-element-4420f3ec > .elementor-widget-container{margin:-12% -10% -20% 0%;}}@media(max-width:767px){.elementor-7158 .elementor-element.elementor-element-4420f3ec > .elementor-widget-container{margin:-12% -16% -10% -18%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"7158\" class=\"elementor elementor-7158\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-44210468 e-flex e-con-boxed e-con e-parent\" data-id=\"44210468\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4420f3ec elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"4420f3ec\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1515\" height=\"1219\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1515 1219&#039;%2F%3E\" class=\"attachment-full size-full wp-image-11980 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/04\/create-processes-and-round-welphi-survey-software.webp\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/04\/create-processes-and-round-welphi-survey-software.webp 1515w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/04\/create-processes-and-round-welphi-survey-software-300x241.webp 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/04\/create-processes-and-round-welphi-survey-software-1024x824.webp 1024w\" data-sizes=\"(max-width: 1515px) 100vw, 1515px\" data-aspect=\"1.2428219852338\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t <\/div><div id=\"lqd-tab-1662\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.elementor-12131 .elementor-element.elementor-element-62b78487{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;}.elementor-12131 .elementor-element.elementor-element-55cc8ad{width:var( --container-widget-width, 770px );max-width:770px;--container-widget-width:770px;--container-widget-flex-grow:0;}.elementor-12131 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-38% -10% -20% 0%;}@media(max-width:1024px){.elementor-12131 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-12% -10% -20% 0%;}}@media(max-width:767px){.elementor-12131 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-12% -16% -10% -18%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"12131\" class=\"elementor elementor-12131\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-62b78487 e-flex e-con-boxed e-con e-parent\" data-id=\"62b78487\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55cc8ad elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"55cc8ad\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"853\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1060 853&#039;%2F%3E\" class=\"attachment-full size-full wp-image-8311 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-Invitation-Customized-Messages.png\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-Invitation-Customized-Messages.png 1060w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-Invitation-Customized-Messages-300x241.png 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-Invitation-Customized-Messages-1024x824.png 1024w\" data-sizes=\"(max-width: 1060px) 100vw, 1060px\" data-aspect=\"1.242672919109\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t <\/div><div id=\"lqd-tab-1663\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.elementor-8285 .elementor-element.elementor-element-b46828c{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;}.elementor-8285 .elementor-element.elementor-element-3b198d36{width:var( --container-widget-width, 770px );max-width:770px;--container-widget-width:770px;--container-widget-flex-grow:0;}.elementor-8285 .elementor-element.elementor-element-3b198d36 > .elementor-widget-container{margin:-38% -10% -20% 0%;}@media(max-width:1024px){.elementor-8285 .elementor-element.elementor-element-3b198d36 > .elementor-widget-container{margin:-12% -10% -20% 0%;}}@media(max-width:767px){.elementor-8285 .elementor-element.elementor-element-3b198d36 > .elementor-widget-container{margin:-12% -16% -10% -18%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8285\" class=\"elementor elementor-8285\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-b46828c e-flex e-con-boxed e-con e-parent\" data-id=\"b46828c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b198d36 elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"3b198d36\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1211\" height=\"974\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1211 974&#039;%2F%3E\" class=\"attachment-full size-full wp-image-8303 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Survey-Round-Statistics.png\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Survey-Round-Statistics.png 1211w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Survey-Round-Statistics-300x241.png 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Survey-Round-Statistics-1024x824.png 1024w\" data-sizes=\"(max-width: 1211px) 100vw, 1211px\" data-aspect=\"1.2433264887064\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t <\/div><div id=\"lqd-tab-1664\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.elementor-8310 .elementor-element.elementor-element-62b78487{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;}.elementor-8310 .elementor-element.elementor-element-55cc8ad{width:var( --container-widget-width, 770px );max-width:770px;--container-widget-width:770px;--container-widget-flex-grow:0;}.elementor-8310 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-38% -10% -20% 0%;}@media(max-width:1024px){.elementor-8310 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-12% -10% -20% 0%;}}@media(max-width:767px){.elementor-8310 .elementor-element.elementor-element-55cc8ad > .elementor-widget-container{margin:-12% -16% -10% -18%;}}<\/style>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8310\" class=\"elementor elementor-8310\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-62b78487 e-flex e-con-boxed e-con e-parent\" data-id=\"62b78487\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55cc8ad elementor-widget__width-initial elementor-widget elementor-widget-ld_fancy_image\" data-id=\"55cc8ad\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1515\" height=\"1219\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1515 1219&#039;%2F%3E\" class=\"attachment-full size-full wp-image-11993 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-survey-software-Collect-demographics.webp\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-survey-software-Collect-demographics.webp 1515w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-survey-software-Collect-demographics-300x241.webp 300w, https:\/\/www.welphi.com\/wp-content\/uploads\/2024\/05\/Welphi-survey-software-Collect-demographics-1024x824.webp 1024w\" data-sizes=\"(max-width: 1515px) 100vw, 1515px\" data-aspect=\"1.2428219852338\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t <\/div><div class=\"lqd-tabs-nav-arrows\">\n\t\t\t\t<button class=\"lqd-tabs-nav-arrow lqd-tabs-nav-prev d-inline-flex align-items-center justify-content-center border-radius-circle pos-abs\">\n\t\t\t\t\t<i class=\"lqd-icn-ess icon-md-arrow-back\"><\/i>\n\t\t\t\t<\/button>\n\t\t\t\t<button class=\"lqd-tabs-nav-arrow lqd-tabs-nav-next d-inline-flex align-items-center justify-content-center border-radius-circle pos-abs\">\n\t\t\t\t\t<i class=\"lqd-icn-ess icon-md-arrow-forward\"><\/i>\n\t\t\t\t<\/button>\n\t\t\t<\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b1c4c1 e-flex e-con-boxed e-con e-parent\" data-id=\"5b1c4c1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1998f91 e-con-full e-flex e-con e-child\" data-id=\"1998f91\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e77eecf elementor-widget__width-inherit elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"e77eecf\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce657506b\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title ld-gradient-heading lqd-highlight-classic lqd-highlight-grow-left h3\"  > Delphi - Como fazemos<\/h3>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dbf589 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-ld_fancy_image\" data-id=\"3dbf589\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"570\" height=\"587\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 570 587&#039;%2F%3E\" class=\"attachment-full size-full wp-image-12156 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/How-to-implemente-delphi-1.webp\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/How-to-implemente-delphi-1.webp 570w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/How-to-implemente-delphi-1-291x300.webp 291w\" data-sizes=\"(max-width: 570px) 100vw, 570px\" data-aspect=\"0.97103918228279\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbbfd3d elementor-widget__width-inherit elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-ld_button\" data-id=\"bbbfd3d\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=CI8M-EPXaH8\" class=\"elementor-button btn btn-solid btn-sm fresco btn-icon-right btn-has-label\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t<span data-text=\"V\u00ea como funciona\" class=\"btn-txt\">\n\t\t\t\t\t\tV\u00ea como funciona\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6beb10 elementor-widget__width-initial elementor-widget elementor-widget-ld_accordion\" data-id=\"a6beb10\" data-element_type=\"widget\" data-widget_type=\"ld_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"accordion accordion-title-underlined accordion-sm\" id=\"accordion-6a56ce65a9896\" role=\"tablist\" aria-multiselectable=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel  active\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1741\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a56ce65a9896\" data-bs-parent=\"#accordion-6a56ce65a9896\" href=\"#collapse-1741\" data-target=\"#collapse-1741\" data-bs-target=\"#collapse-1741\"\n\t\t\t\t\taria-expanded=\"true\" aria-controls=\"collapse-1741\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Configura o teu processo com rondas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1741\" class=\"accordion-collapse collapse  show\" data-bs-parent=\"#accordion-6a56ce65a9896\" role=\"tabpanel\" aria-labelledby=\"heading-1741\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>O Welphi implementa o m\u00e9todo Delphi por rondas. Ter\u00e1 de criar uma ronda para come\u00e7ar a obter as respostas e o feedback dos participantes. Para chegar a um consenso, pode criar rondas adicionais. Em cada ronda, o Welphi mostra automaticamente as estat\u00edsticas e os coment\u00e1rios das rondas anteriores e permite que os participantes revejam as suas respostas.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1742\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a56ce65a9896\" data-bs-parent=\"#accordion-6a56ce65a9896\" href=\"#collapse-1742\" data-target=\"#collapse-1742\" data-bs-target=\"#collapse-1742\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1742\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Criar p\u00e1ginas<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1742\" class=\"accordion-collapse collapse \" data-bs-parent=\"#accordion-6a56ce65a9896\" role=\"tabpanel\" aria-labelledby=\"heading-1742\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>Cada ronda pode incluir diferentes tipos de p\u00e1ginas, dependendo do tipo de dados que precisas de recolher. Pode incluir p\u00e1ginas qualitativas, em que os participantes respondem com uma escala, p\u00e1ginas quantitativas, em que as pessoas s\u00e3o convidadas a responder a um n\u00famero dentro de um intervalo predefinido ou p\u00e1ginas de classifica\u00e7\u00e3o, em que os participantes s\u00f3 precisam de arrastar e largar para classificar um conjunto predefinido de itens<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1743\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a56ce65a9896\" data-bs-parent=\"#accordion-6a56ce65a9896\" href=\"#collapse-1743\" data-target=\"#collapse-1743\" data-bs-target=\"#collapse-1743\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1743\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Produzir e partilhar estat\u00edsticas  <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1743\" class=\"accordion-collapse collapse \" data-bs-parent=\"#accordion-6a56ce65a9896\" role=\"tabpanel\" aria-labelledby=\"heading-1743\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>Ao longo de todo o processo, o Welphi fornece estat\u00edsticas autom\u00e1ticas das respostas dos participantes e disponibiliza-as no in\u00edcio da ronda seguinte, juntamente com quaisquer coment\u00e1rios que possam ter sido fornecidos. Com esta informa\u00e7\u00e3o, os participantes s\u00e3o convidados a rever as suas respostas.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1744\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a56ce65a9896\" data-bs-parent=\"#accordion-6a56ce65a9896\" href=\"#collapse-1744\" data-target=\"#collapse-1744\" data-bs-target=\"#collapse-1744\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1744\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Cria regras para aprova\u00e7\u00e3o e rejei\u00e7\u00e3o  <\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1744\" class=\"accordion-collapse collapse \" data-bs-parent=\"#accordion-6a56ce65a9896\" role=\"tabpanel\" aria-labelledby=\"heading-1744\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p><span style=\"font-weight: 400;\">No final de cada ronda, o Welphi permite-lhe definir regras de aceita\u00e7\u00e3o ou rejei\u00e7\u00e3o com base nas quais qualquer item do objeto de estudo pode ser aprovado, rejeitado ou deixado sem classifica\u00e7\u00e3o para rondas posteriores.<\/span><\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Configura o teu processo com rondas\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"O Welphi implementa o mtodo Delphi por rondas. Ter de criar uma ronda para comear a obter as respostas e o feedback dos participantes. Para chegar a um consenso, pode criar rondas adicionais. Em cada ronda, o Welphi mostra automaticamente as estatsticas e os comentrios das rondas anteriores e permite que os participantes revejam as suas respostas.\"}},{\"@type\":\"Question\",\"name\":\"Criar p\\u00e1ginas\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Cada ronda pode incluir diferentes tipos de pginas, dependendo do tipo de dados que precisas de recolher. Pode incluir pginas qualitativas, em que os participantes respondem com uma escala, pginas quantitativas, em que as pessoas so convidadas a responder a um nmero dentro de um intervalo predefinido ou pginas de classificao, em que os participantes s precisam de arrastar e largar para classificar um conjunto predefinido de itens\"}},{\"@type\":\"Question\",\"name\":\"Produzir e partilhar estat\\u00edsticas\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Ao longo de todo o processo, o Welphi fornece estatsticas automticas das respostas dos participantes e disponibiliza-as no incio da ronda seguinte, juntamente com quaisquer comentrios que possam ter sido fornecidos. Com esta informao, os participantes so convidados a rever as suas respostas.\"}},{\"@type\":\"Question\",\"name\":\"Cria regras para aprova\\u00e7\\u00e3o e rejei\\u00e7\\u00e3o\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"No final de cada ronda, o Welphi permite-lhe definir regras de aceitao ou rejeio com base nas quais qualquer item do objeto de estudo pode ser aprovado, rejeitado ou deixado sem classificao para rondas posteriores.\"}}]}<\/script>\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39e40e6 e-con-full e-flex e-con e-child\" data-id=\"39e40e6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d230e8 elementor-hidden-mobile elementor-widget elementor-widget-ld_fancy_image\" data-id=\"4d230e8\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"570\" height=\"587\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 570 587&#039;%2F%3E\" class=\"attachment-full size-full wp-image-12156 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/How-to-implemente-delphi-1.webp\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/How-to-implemente-delphi-1.webp 570w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/How-to-implemente-delphi-1-291x300.webp 291w\" data-sizes=\"(max-width: 570px) 100vw, 570px\" data-aspect=\"0.97103918228279\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-866309c elementor-widget__width-inherit elementor-align-center elementor-widget elementor-widget-ld_button\" data-id=\"866309c\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/www.youtube.com\/watch?v=CI8M-EPXaH8\" class=\"elementor-button btn btn-solid btn-sm fresco btn-icon-right btn-has-label\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t<span data-text=\"V\u00ea como funciona\" class=\"btn-txt\">\n\t\t\t\t\t\tV\u00ea como funciona\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45ec6b3 e-flex e-con-boxed e-con e-parent\" data-id=\"45ec6b3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5de9bb3 e-con-full e-flex e-con e-child\" data-id=\"5de9bb3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3de2cdd elementor-hidden-mobile elementor-widget elementor-widget-ld_fancy_image\" data-id=\"3de2cdd\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1188\" height=\"1223\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 1188 1223&#039;%2F%3E\" class=\"attachment-full size-full wp-image-12109 ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/welphi-how-we-implemente-mcda-survey-software_How-we-implemente-mcda-welphi-survey-software.webp\" data-srcset=\"https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/welphi-how-we-implemente-mcda-survey-software_How-we-implemente-mcda-welphi-survey-software.webp 1188w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/welphi-how-we-implemente-mcda-survey-software_How-we-implemente-mcda-welphi-survey-software-291x300.webp 291w, https:\/\/www.welphi.com\/wp-content\/uploads\/2025\/04\/welphi-how-we-implemente-mcda-survey-software_How-we-implemente-mcda-welphi-survey-software-995x1024.webp 995w\" data-sizes=\"(max-width: 1188px) 100vw, 1188px\" data-aspect=\"0.97138184791496\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4e3fd3c e-con-full e-flex e-con e-child\" data-id=\"4e3fd3c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-693f6ac elementor-widget__width-inherit elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"693f6ac\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce661a814\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title ld-gradient-heading lqd-highlight-classic lqd-highlight-grow-left h3\"  > MCDA - <br> Como Fazemos<\/h3>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ef2770 elementor-widget elementor-widget-ld_accordion\" data-id=\"8ef2770\" data-element_type=\"widget\" data-widget_type=\"ld_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"accordion accordion-title-underlined accordion-sm\" id=\"accordion-6a56ce661b0b6\" role=\"tablist\" aria-multiselectable=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel  active\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1491\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a56ce661b0b6\" data-bs-parent=\"#accordion-6a56ce661b0b6\" href=\"#collapse-1491\" data-target=\"#collapse-1491\" data-bs-target=\"#collapse-1491\"\n\t\t\t\t\taria-expanded=\"true\" aria-controls=\"collapse-1491\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">O m\u00e9todo MACBETH<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1491\" class=\"accordion-collapse collapse  show\" data-bs-parent=\"#accordion-6a56ce661b0b6\" role=\"tabpanel\" aria-labelledby=\"heading-1491\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>A recolha de prefer\u00eancias para avaliar as op\u00e7\u00f5es implica a pontua\u00e7\u00e3o de cada op\u00e7\u00e3o e a pondera\u00e7\u00e3o de cada crit\u00e9rio. Para estes dois processos, implementamos o m\u00e9todo MACBETH.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1492\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a56ce661b0b6\" data-bs-parent=\"#accordion-6a56ce661b0b6\" href=\"#collapse-1492\" data-target=\"#collapse-1492\" data-bs-target=\"#collapse-1492\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1492\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Pondera\u00e7\u00e3o de balan\u00e7o<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1492\" class=\"accordion-collapse collapse \" data-bs-parent=\"#accordion-6a56ce661b0b6\" role=\"tabpanel\" aria-labelledby=\"heading-1492\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>A pondera\u00e7\u00e3o dos crit\u00e9rios \u00e9 um dos passos mais essenciais na avalia\u00e7\u00e3o de op\u00e7\u00f5es. No Welphi, implementamos a Pondera\u00e7\u00e3o Swing qualitativa. Basta inserir os crit\u00e9rios e as suas refer\u00eancias, e o Welphi cria automaticamente o question\u00e1rio para ti.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1493\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a56ce661b0b6\" data-bs-parent=\"#accordion-6a56ce661b0b6\" href=\"#collapse-1493\" data-target=\"#collapse-1493\" data-bs-target=\"#collapse-1493\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1493\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Pontua\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1493\" class=\"accordion-collapse collapse \" data-bs-parent=\"#accordion-6a56ce661b0b6\" role=\"tabpanel\" aria-labelledby=\"heading-1493\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>Para pontuar as op\u00e7\u00f5es em cada crit\u00e9rio, cria escalas de valores. Basta inserir os n\u00edveis de refer\u00eancia de cada crit\u00e9rio, e o Welphi criar\u00e1 question\u00e1rios de pontua\u00e7\u00e3o implementando o m\u00e9todo MACBETH.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1494\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a56ce661b0b6\" data-bs-parent=\"#accordion-6a56ce661b0b6\" href=\"#collapse-1494\" data-target=\"#collapse-1494\" data-bs-target=\"#collapse-1494\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1494\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">Sa\u00eddas do processo<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-add\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-remove\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1494\" class=\"accordion-collapse collapse \" data-bs-parent=\"#accordion-6a56ce661b0b6\" role=\"tabpanel\" aria-labelledby=\"heading-1494\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>Depois de lan\u00e7ar os question\u00e1rios e recolher todas as respostas, o Welphi fornece escalas e pesos para cada participante. Esta informa\u00e7\u00e3o permite-lhe compreender as prefer\u00eancias dos seus participantes relativamente aos crit\u00e9rios e avaliar as op\u00e7\u00f5es.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"O m\\u00e9todo MACBETH\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A recolha de preferncias para avaliar as opes implica a pontuao de cada opo e a ponderao de cada critrio. Para estes dois processos, implementamos o mtodo MACBETH.\"}},{\"@type\":\"Question\",\"name\":\"Pondera\\u00e7\\u00e3o de balan\\u00e7o\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"A ponderao dos critrios  um dos passos mais essenciais na avaliao de opes. No Welphi, implementamos a Ponderao Swing qualitativa. Basta inserir os critrios e as suas referncias, e o Welphi cria automaticamente o questionrio para ti.\"}},{\"@type\":\"Question\",\"name\":\"Pontua\\u00e7\\u00e3o\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Para pontuar as opes em cada critrio, cria escalas de valores. Basta inserir os nveis de referncia de cada critrio, e o Welphi criar questionrios de pontuao implementando o mtodo MACBETH.\"}},{\"@type\":\"Question\",\"name\":\"Sa\\u00eddas do processo\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Depois de lanar os questionrios e recolher todas as respostas, o Welphi fornece escalas e pesos para cada participante. Esta informao permite-lhe compreender as preferncias dos seus participantes relativamente aos critrios e avaliar as opes.\"}}]}<\/script>\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope .e-con-inner &gt; .e-con&quot;,&quot;duration&quot;:1000,&quot;delay&quot;:75,&quot;ease&quot;:&quot;expo.out&quot;,&quot;initValues&quot;:{&quot;scaleX&quot;:1.3,&quot;scaleY&quot;:1.3,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;scaleX&quot;:1,&quot;scaleY&quot;:1,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-element elementor-element-782613f0 e-flex e-con-boxed e-con e-parent\" data-id=\"782613f0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-212062a2 elementor-widget__width-inherit elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"212062a2\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce661b615\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h3 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h3\"  > Inscreve-te para um teste gratuito de 14 dias.<\/h3>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aceb680 e-flex e-con-boxed e-con e-child\" data-id=\"aceb680\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"lqd-iconbox-scale elementor-element elementor-element-298d8c4a elementor-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-ld_icon_box\" data-id=\"298d8c4a\" data-element_type=\"widget\" data-settings=\"{&quot;enable_scale_animation&quot;:&quot;yes&quot;}\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id=\"ld_icon_box_298d8c4a\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-column iconbox-default iconbox-icon-shaped iconbox-circle iconbox-contents-show-onhover\"   data-slideelement-onhover=\"true\" data-slideelement-options='{ \"visibleElement\": \".iconbox-icon-wrap, p, p\", \"hiddenElement\": \".btn\", \"alignMid\": true, \"triggerElement\": \".elementor-widget-container\" }'>\n\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex pos-rel z-index-1 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-num-1\"><\/i><\/div><\/div>\n\t\t\t\t<p class=\"lqd-iconbox-heading \" >Subscrever <\/p>\n\t\t\t\t<div class=\"contents \">\n\t\t\t\t\n\t\t\t\t\t\t\t\t<p>Nome e e-mail<\/p>\n\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"lqd-iconbox-scale elementor-element elementor-element-61f87551 elementor-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-ld_icon_box\" data-id=\"61f87551\" data-element_type=\"widget\" data-settings=\"{&quot;enable_scale_animation&quot;:&quot;yes&quot;}\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id=\"ld_icon_box_61f87551\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-column iconbox-default iconbox-icon-shaped iconbox-circle iconbox-contents-show-onhover\"   data-slideelement-onhover=\"true\" data-slideelement-options='{ \"visibleElement\": \".iconbox-icon-wrap, p, p\", \"hiddenElement\": \".btn\", \"alignMid\": true, \"triggerElement\": \".elementor-widget-container\" }'>\n\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex pos-rel z-index-1 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-num-2\"><\/i><\/div><\/div>\n\t\t\t\t<p class=\"lqd-iconbox-heading \" >Definir palavra-passe <\/p>\n\t\t\t\t<div class=\"contents \">\n\t\t\t\t\n\t\t\t\t\t\t\t\t<p>Criar e confirmar<\/p>\n\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"lqd-iconbox-scale elementor-element elementor-element-34080fcd elementor-align-center elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-ld_icon_box\" data-id=\"34080fcd\" data-element_type=\"widget\" data-settings=\"{&quot;enable_scale_animation&quot;:&quot;yes&quot;}\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id=\"ld_icon_box_34080fcd\" class=\"iconbox d-flex flex-grow-1 pos-rel flex-column iconbox-default iconbox-icon-shaped iconbox-circle iconbox-contents-show-onhover\"   data-slideelement-onhover=\"true\" data-slideelement-options='{ \"visibleElement\": \".iconbox-icon-wrap, p, p\", \"hiddenElement\": \".btn\", \"alignMid\": true, \"triggerElement\": \".elementor-widget-container\" }'>\n\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex pos-rel z-index-1 border-radius-circle\"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-num-3\"><\/i><\/div><\/div>\n\t\t\t\t<p class=\"lqd-iconbox-heading \" >Termos e condi\u00e7\u00f5es <\/p>\n\t\t\t\t<div class=\"contents \">\n\t\t\t\t\n\t\t\t\t\t\t\t\t<p>D\u00e1 o teu consentimento<\/p>\n\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fed734 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-ld_button\" data-id=\"0fed734\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a href=\"https:\/\/app2.welphi.com\/Pages\/LoginPage.aspx?trial=1\" class=\"elementor-button btn btn-solid btn-hover-txt-switch btn-hover-txt-switch-y btn-xsm btn-icon-right btn-has-label\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t\t\t<span data-text=\"Teste Gratuito\" class=\"btn-txt\" data-transition-delay=\"true\" data-delay-options=\"{&quot;elements&quot;: &quot;.lqd-chars&quot;, &quot;delayType&quot;: &quot;animation&quot;, &quot;startDelay&quot;: 0, &quot;delayBetween&quot;: 32.5}\" data-split-text=\"true\" data-split-options=\"{&quot;type&quot;: &quot;chars, words&quot;}\">\n\t\t\t\t\t\tTeste Gratuito\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-md-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-134f26a4 e-flex e-con-boxed e-con e-parent\" data-id=\"134f26a4\" data-element_type=\"container\" id=\"demo\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope .e-con-inner &gt; .elementor-element:not(.lqd-exclude-parent-ca) &gt; .elementor-widget-container, :scope .e-con-inner &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope .e-con-inner &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope .e-con-inner &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope .e-con-inner &gt; .elementor-widget-hub_fancy_heading .lqd-adv-txt-fig, :scope .e-con-inner &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li, :scope .e-con:not([data-parallax]) .elementor-element &gt; .elementor-widget-container, :scope .e-con:not([data-parallax]) .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope .e-con:not([data-parallax]) .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope .e-con:not([data-parallax]) .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope .e-con:not([data-parallax]) .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:750,&quot;delay&quot;:75,&quot;ease&quot;:&quot;expo.out&quot;,&quot;initValues&quot;:{&quot;y&quot;:&quot;60px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-element elementor-element-72d14b99 e-flex e-con-boxed e-con e-child\" data-id=\"72d14b99\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-690cbc59 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"690cbc59\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce6620635\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Vamos marcar<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142bb62b elementor-hidden-mobile elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"142bb62b\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce6620b66\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title ld-gradient-heading lqd-highlight-classic lqd-highlight-grow-left h2\"  > uma demonstra\u00e7\u00e3o ao vivo<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d6887d elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"2d6887d\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce6621573\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title ld-gradient-heading lqd-highlight-classic lqd-highlight-grow-left h2\"  > uma demo<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45e92752 elementor-widget__width-initial elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"45e92752\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce6621cae\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > O Welphi \u00e9 o espa\u00e7o de trabalho tudo-em-um com m\u00e9todos de tomada de decis\u00e3o com carater\u00edsticas exclusivas e navega\u00e7\u00e3o f\u00e1cil de utilizar. Cria facilmente processos, convida participantes, inicia e p\u00e1ra uma ronda, analisa a conclus\u00e3o e a rejei\u00e7\u00e3o, define mensagens personalizadas e obt\u00e9m integra\u00e7\u00e3o estat\u00edstica. <\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ca7e05 button-demo elementor-widget elementor-widget-button\" data-id=\"6ca7e05\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver Disponibilidade<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e6150f0 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"7e6150f0\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a56ce66221d4\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > 1. Escolha Data e Hora      2. Partilhe o nome \n e o e-mail       3. Confirme<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fdf434 e-flex e-con-boxed e-con e-parent\" data-id=\"1fdf434\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad0f9e8 elementor-widget elementor-widget-ld_hotspots\" data-id=\"ad0f9e8\" data-element_type=\"widget\" data-widget_type=\"ld_hotspots.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div class=\"lqd-hotspot pos-rel\">\n\t\t\t\t<div class=\"lqd-hotspot-inner\">\n\n\t\t\t\t\t<div class=\"lqd-hotspot-img\">\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"lqd-hotspot-items lqd-overlay\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Software de Question\u00e1rio Online Welphi M\u00e9todos para uma tomada de decis\u00e3o Constr\u00f3i question\u00e1rios que implementam o m\u00e9todo Delphi ou MCDA para uma tomada de decis\u00e3o s\u00f3lida e baseada em prefer\u00eancias em diversos dom\u00ednios. Teste Gratuito Marcar Demo Testar Demo Teste gratuito de 14 dias &#8211; Suporte exclusivo &#8211; Ambiente em cloud Utilizado por organiza\u00e7\u00f5es de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10881","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.welphi.com\/pt-pt\/wp-json\/wp\/v2\/pages\/10881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welphi.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.welphi.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.welphi.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welphi.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=10881"}],"version-history":[{"count":76,"href":"https:\/\/www.welphi.com\/pt-pt\/wp-json\/wp\/v2\/pages\/10881\/revisions"}],"predecessor-version":[{"id":13426,"href":"https:\/\/www.welphi.com\/pt-pt\/wp-json\/wp\/v2\/pages\/10881\/revisions\/13426"}],"wp:attachment":[{"href":"https:\/\/www.welphi.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=10881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}